{"id":2518,"date":"2026-07-13T16:07:59","date_gmt":"2026-07-13T15:07:59","guid":{"rendered":"https:\/\/ciaotable.org\/?page_id=2518"},"modified":"2026-07-15T07:54:00","modified_gmt":"2026-07-15T06:54:00","slug":"salutare-e-salutare","status":"publish","type":"page","link":"https:\/\/ciaotable.org\/de\/salutare-e-salutare\/","title":{"rendered":"Salutare \u00e8 salutare"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#083DA7&#8243; custom_padding=&#8221;48px||0px||false|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; border_width_top=&#8221;5px&#8221; border_color_top=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;50%&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;40px&#8221; text_line_height=&#8221;1.2em&#8221; header_font=&#8221;&#8211;et_global_body_font|600|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;||10px||false|false&#8221; text_font_size_tablet=&#8221;34px&#8221; text_font_size_phone=&#8221;22px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ciaotable.org\/wp-content\/uploads\/2025\/01\/MARCHIO_BIANCO_cropped-269x300.png\" width=\"119\" height=\"132\" alt=\"\" class=\"wp-image-1172 alignnone size-medium\" srcset=\"https:\/\/ciaotable.org\/wp-content\/uploads\/2025\/01\/MARCHIO_BIANCO_cropped-269x300.png 269w, https:\/\/ciaotable.org\/wp-content\/uploads\/2025\/01\/MARCHIO_BIANCO_cropped.png 310w\" sizes=\"(max-width: 119px) 100vw, 119px\" \/><\/strong><\/p>\n<p class=\"p1\"><strong>Campagna del saluto a&#8230;<br \/>chi ti \u00e8 vicino<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\">Unisciti alla campagna del saluto di <strong><span class=\"s1\"><i style=\"color: #ee7d00;\">Ciao Table<\/i><\/span><\/strong><span class=\"s2\">. P<\/span>ratichiamo il saluto alle persone vicine nei locali pubblici: vicine di tavolo, di ombrellone, di panchina o di posto nei cinema, teatri, esercizi commerciali, uffici pubblici.<span class=\"Apple-converted-space\"> <\/span>Perch\u00e9:<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;40px&#8221; text_line_height=&#8221;1.2em&#8221; header_font=&#8221;&#8211;et_global_body_font|600|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;60px||6px||false|false&#8221; custom_padding=&#8221;||10px||false|false&#8221; text_font_size_tablet=&#8221;34px&#8221; text_font_size_phone=&#8221;22px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><i>SALUTARE \u00c8\u2026 <\/i>SALUTARE<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;8px||8px||true|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\"><b>Studi scientifici dimostrano che un saluto<\/b> <b>pu\u00f2 far bene a te e anche a chi lo riceve.<\/b><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;8px||8px||true|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\">La letteratura scientifica riconosce da tempo<b> le connessioni sociali come un fondamentale fattore di protezione della salute psicofisica.<\/b><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;8px||8px||true|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\">Infatti \u00e8 scientificamente provato che <b>la scarsit\u00e0 di connessioni sociali aumenta il rischio di mortalit\u00e0 precoce<\/b> (dal 33% al 50%, a seconda degli studi), aumenta la probabilit\u00e0 di ansia, depressione e di sviluppare demenza. Inoltre, le connessioni sociali aumentano <b>l\u2019efficacia della risposta immunitaria<\/b>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221; text_font_size=&#8221;14px&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p class=\"p1\"><b>Per maggiori informazioni, vedi la <a href=\"https:\/\/ciaotable.org\/bibliografia\/\" style=\"color: #ffffff; text-decoration: underline;\">nostra Bibliografia<\/a><\/b><b> e in particolare Holt-Lunstad, J. (2020). The double pandemic of social isolation and COVID-19: Cross-sector policy must address both. <\/b><b><i>Health Affairs Forefront<\/i><\/b><b>. e Naito, R., McKee, M., Leong, D., Bangdiwala, S., Rangarajan, S., Islam, S., &amp; Yusuf, S. (2023). Social isolation as a risk factor for all-cause mortality: Systematic review and meta-analysis of cohort studies. <\/b><b><i>PloS one<\/i><\/b><b>, <\/b><b><i>18<\/i><\/b><b>(1), e0280308.<\/b><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;8px||8px||true|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\"><b><\/b><\/p>\n<p class=\"p2\">Recenti studi mostrano inoltre che <b>anche minimi scambi sociali con persone sconosciute contribuiscono al benessere soggettivo<\/b>:<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221; text_font_size=&#8221;14px&#8221;]<\/p>\n<p class=\"p1\"><b>Epley, N., Akalis, S., Waytz, A., &amp; Cacioppo, J. T. (2008). Creating social connection through inferential reproduction: Loneliness and perceived agency in gadgets, gods, and greyhounds.\u00a0<\/b><b><i>Psychological science<\/i><\/b><b>,\u00a0<\/b><b><i>19<\/i><\/b><b>(2), 114-120.<\/b><\/p>\n<p class=\"p1\"><b>Gunaydin, G., Oztekin, H., Karabulut, D. H., &amp; Salman-Engin, S. (2021). Minimal social interactions with strangers predict greater subjective well-being.\u00a0<\/b><b><i>Journal of Happiness Studies<\/i><\/b><b>,\u00a0<\/b><b><i>22<\/i><\/b><b>).<\/b><\/p>\n<p class=\"p1\"><b>Sandstrom, G. M., &amp; Dunn, E. W. (2014). Social interactions and well-being: The surprising power of weak ties.\u00a0<\/b><b><i>Personality and Social Psychology Bulletin<\/i><\/b><b>,\u00a0<\/b><b><i>40<\/i><\/b><b>(7), 910-922.<\/b><\/p>\n<p class=\"p1\"><b>Sandstrom, G. M., &amp; Boothby, E. J. (2021). Why do people avoid talking to strangers? A mini meta-analysis of predicted fears and actual experiences talking to a stranger.\u00a0<\/b><b><i>Self and identity<\/i><\/b><b>,\u00a0<\/b><b><i>20<\/i><\/b><b>(1), 47-71.<\/b><\/p>\n<p class=\"p1\"><b>Sandstrom, G. M., Boothby, E. J., &amp; Cooney, G. (2022). Talking to strangers: A week-long intervention reduces psychological barriers to social connection.\u00a0<\/b><b><i>Journal of Experimental Social Psychology<\/i><\/b><b>,\u00a0<\/b><b><i>102<\/i><\/b><b>, 104356.<\/b><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;8px||8px||true|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\"><b>Il saluto, oltre a contribuire al benessere soggettivo, agisce come facilitatore di scambio sociale<\/b>; \u00e8 infatti evidente che rende pi\u00f9 probabile l\u2019avvio di una conversazione, almeno nei casi in cui entrambe le parti siano desiderose di realizzarla.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;8px||8px||true|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\">Attraverso sondaggi e osservazioni abbiamo rilevato che nelle citt\u00e0 il saluto alle persone vicine non \u00e8 certamente abituale, ma non \u00e8 neppure del tutto inusuale: il nostro appello intende stimolare <b>una pratica congrua con la nostra cultura<\/b>.<\/p>\n<p class=\"p2\"><b><i><\/i><\/b><\/p>\n<p class=\"p1\">Questa campagna persegue l\u2019obiettivo che le due associazioni <strong><span class=\"s1\"><i style=\"color: #ee7d00;\">Ciao Table<\/i><\/span><\/strong><span class=\"s2\"> e<span class=\"Apple-converted-space\">\u00a0 <\/span><i>Psychology and Psychotherapy Research Society <\/i>si sono poste a partire dal 2017: <b>promuovere nel territorio una cultura che sempre pi\u00f9 faciliti positivi scambi sociali.<\/b><\/p>\n<p class=\"p2\">\n<p class=\"p1\">L\u2019iniziativa si realizza in continuit\u00e0 con i progetti scientifici nonch\u00e9 socio-culturali gi\u00e0 realizzati per la promozione degli scambi sociali: convegni scientifici, <i>Social Research Prize<\/i>, \u201cPorte Aperte delle associazioni culturali che offrono attivit\u00e0 per il tempo libero\u201d, Consulenze sul tempo libero ecc.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;8px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\"><b>Le nostre citt\u00e0 diventeranno ancor pi\u00f9 salubri e accoglienti.<\/b><\/p>\n<p class=\"p1\">Viverci sar\u00e0 ancor pi\u00f9 piacevole, visitarle ancor pi\u00f9 gradevole.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;40px&#8221; text_line_height=&#8221;1.2em&#8221; header_font=&#8221;&#8211;et_global_body_font|600|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;24px||6px||false|false&#8221; custom_padding=&#8221;||10px||false|false&#8221; text_font_size_tablet=&#8221;34px&#8221; text_font_size_phone=&#8221;22px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"p1\">Ecco alcune testimonianze dei-lle nostre-i &#8220;attiviste-i del saluto&#8221;:<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;8px||8px||true|false&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover=&#8221;#F2F2F2&#8243; text_text_color__hover_enabled=&#8221;on|hover&#8221;]<\/p>\n<p class=\"p1\"><b>Eva<\/b>: <i>Ieri in pizzeria con mio marito abbiamo applicato la \u201cpratica del saluto <\/i><strong><span class=\"s1\"><i style=\"color: #ee7d00;\">Ciao Table<\/i><\/span><\/strong><span class=\"s2\">\u201d e cio\u00e8, semplicemente, sedendoci, abbiamo salutato la coppia al tavolo vicino. Ne \u00e8 nata una lunga conversazione\u2026 Sono cose che danno un po\u2019 di allegria<\/i>.<\/p>\n<p class=\"p2\"><b><\/b><\/p>\n<p class=\"p1\"><b>Marco<\/b>: <i>Al cinema io adesso saluto chi si siede al mio fianco. In genere non si va oltre il semplice saluto. Comunque mi fa piacere.<\/i><\/p>\n<p class=\"p2\"><i><\/i><\/p>\n<p class=\"p1\"><b>Natasha<\/b>: <i>Stamattina salendo sul bus ho salutato la donna che era di fronte a me. Lei mi ha guardata, ma non mi ha risposto. Pazienza: non ci sono rimasta male perch\u00e9 salutare \u00e8 una cosa giusta.<\/i><\/p>\n<p class=\"p2\">\n<p class=\"p1\"><b>Alexander<\/b>: <i>Io in genere tendo a salutare per esempio nelle sale di attesa degli ambulatori o l\u2019autista quando salgo sul bus. L\u2019altro giorno ho salutato anche gli altri clienti in fila alla cassa della banca: una signora mi ha chiesto un\u2019informazione e abbiamo chiacchierato un po\u2019<\/i>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;32px&#8221; text_line_height=&#8221;1.2em&#8221; header_font=&#8221;&#8211;et_global_body_font|600|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;24px||6px||false|false&#8221; custom_padding=&#8221;||10px||false|false&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;34px&#8221; text_font_size_phone=&#8221;22px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p class=\"p1\"><span class=\"s1\"><b><i>I media locali su la <\/i><\/b>\u201c<\/span><i>Campagna del saluto a\u2026 chi ti \u00e8 vicino<\/i><span class=\"s1\">\u201d<\/span><\/p>\n<p>[\/et_pb_text][ba_image_carousel slide_count=&#8221;4&#8243; nav_height=&#8221;48px&#8221; nav_width=&#8221;48px&#8221; nav_color=&#8221;#ffffff&#8221; nav_bg=&#8221;#3979ff&#8221; icon_left=&#8221;&#xf104;||fa||900&#8243; icon_right=&#8221;&#xf105;||fa||900&#8243; content_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; subtitle_text_color=&#8221;#F2F2F2&#8243; subtitle_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][ba_image_carousel_child photo=&#8221;https:\/\/ciaotable.org\/wp-content\/uploads\/2026\/07\/589748-z76gst-SEIDISERA-Magazine-Angelica-Arbasini.png&#8221; _builder_version=&#8221;4.27.7&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; title_text=&#8221;589748-z76gst-SEIDISERA-Magazine-Angelica-Arbasini&#8221; link_option_url=&#8221;https:\/\/www.rsi.ch\/rete-uno\/programmi\/intrattenimento\/seidisera-magazine\/&#8221; link_option_url_new_window=&#8221;on&#8221; title=&#8221;Angelica Arbasini&#8221; sub_title=&#8221;Censura, <br \/>SEIDISERA Magazine&#8221; title_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; title_text_color=&#8221;#F2F2F2&#8243; sticky_enabled=&#8221;0&#8243;][\/ba_image_carousel_child][ba_image_carousel_child photo=&#8221;https:\/\/ciaotable.org\/wp-content\/uploads\/2026\/07\/scambi-sociali.webp&#8221; _builder_version=&#8221;4.27.7&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; link_option_url_new_window=&#8221;on&#8221; link_option_url=&#8221;https:\/\/ciaotable.org\/wp-content\/uploads\/2026\/07\/SRP_29.05.2026LaRegione_intervistaCT.pdf&#8221; sticky_enabled=&#8221;0&#8243; title_text=&#8221;scambi-sociali&#8221; title=&#8221;Beatrice Reali&#8221; sub_title=&#8221;\u00abGli scambi sociali<br \/> allungano la vita\u00bb&#8221; title_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; title_text_color=&#8221;#F2F2F2&#8243;][\/ba_image_carousel_child][ba_image_carousel_child photo=&#8221;https:\/\/ciaotable.org\/wp-content\/uploads\/2026\/07\/3780307-75q5fa-Ciao-Table-Tavolo-condiviso.jpeg&#8221; _builder_version=&#8221;4.27.7&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; title_text=&#8221;3780307-75q5fa-Ciao-Table-Tavolo-condiviso&#8221; link_option_url_new_window=&#8221;on&#8221; link_option_url=&#8221;https:\/\/www.rsi.ch\/rete-uno\/programmi\/intrattenimento\/passaggi\/Premio-per-la-ricerca-sociale&#8211;3780310.html&#8221; sticky_enabled=&#8221;0&#8243; title=&#8221;Isabella Visetti&#8221; sub_title=&#8221;\u00abPremio per<br \/> la ricerca sociale\u00bb&#8221; title_text_color=&#8221;#F2F2F2&#8243; title_font=&#8221;&#8211;et_global_heading_font||||||||&#8221;][\/ba_image_carousel_child][\/ba_image_carousel][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;&#8211;et_global_body_font|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;40px&#8221; text_line_height=&#8221;1.2em&#8221; header_font=&#8221;&#8211;et_global_body_font|600|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;24px||6px||false|false&#8221; custom_padding=&#8221;||10px||false|false&#8221; text_font_size_tablet=&#8221;34px&#8221; text_font_size_phone=&#8221;22px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;28px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"p1\">Diventa anche tu attivista del saluto e invia la tua testimonianza a <a href=\"mailto:info@ciaotable.org\" style=\"color: #ffffff; text-decoration: underline;\">info@ciaotable.org<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f37111&#8243; min_height=&#8221;50px&#8221; height=&#8221;50px&#8221; custom_padding=&#8221;||0px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campagna del saluto a&#8230;chi ti \u00e8 vicinoUnisciti alla campagna del saluto di Ciao Table. Pratichiamo il saluto alle persone vicine nei locali pubblici: vicine di tavolo, di ombrellone, di panchina o di posto nei cinema, teatri, esercizi commerciali, uffici pubblici. Perch\u00e9:SALUTARE \u00c8\u2026 SALUTAREStudi scientifici dimostrano che un saluto pu\u00f2 far bene a te e anche [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2518","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ciaotable.org\/de\/wp-json\/wp\/v2\/pages\/2518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciaotable.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ciaotable.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ciaotable.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciaotable.org\/de\/wp-json\/wp\/v2\/comments?post=2518"}],"version-history":[{"count":10,"href":"https:\/\/ciaotable.org\/de\/wp-json\/wp\/v2\/pages\/2518\/revisions"}],"predecessor-version":[{"id":2551,"href":"https:\/\/ciaotable.org\/de\/wp-json\/wp\/v2\/pages\/2518\/revisions\/2551"}],"wp:attachment":[{"href":"https:\/\/ciaotable.org\/de\/wp-json\/wp\/v2\/media?parent=2518"}],"curies":[{"name":"wordpress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}